{"id":3597,"date":"2022-03-31T11:54:53","date_gmt":"2022-03-31T11:54:53","guid":{"rendered":"https:\/\/ordertactics.es\/?p=3597"},"modified":"2022-04-01T13:14:59","modified_gmt":"2022-04-01T13:14:59","slug":"gestion-y-planificacion-del-servicio-domestico","status":"publish","type":"post","link":"https:\/\/ordertactics.es\/en\/alex-m-organizer\/gestion-y-planificacion-del-servicio-domestico\/","title":{"rendered":"Management and planning of domestic service"},"content":{"rendered":"<section id=\"ut-section-6a047c36311e0\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-cursor-skin=\"global\" class=\"vc_section ut-vc-160 vc_section-has-no-fill ut-section-6a047c36311eb\"><div id=\"ut-row-6a047c36319e8\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_column-gap-0 ut-row-6a047c36319f2\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\" ><div id=\"ut_inner_column_6a047c36320a8\" class=\"vc_column-inner\" ><div class=\"wpb_wrapper\"><div class=\"wpb_content_element  vc_custom_1648816167616\"><style type=\"text\/css\">#ut_header_6a047c3632608 h2.section-title { font-size:70px !important;line-height:70px !important;letter-spacing:-0.03em; }<\/style><header id=\"ut_header_6a047c3632608\" class=\"section-header  ut-no-title-linebreak-mobile ut-no-lead-linebreak-mobile pt-style-2 header-left header-tablet-left header-mobile-center element-with-custom-line-height\"><div class=\"element-with-custom-line-height\" ><h2 data-title=\"Gesti\u00f3n y planificaci\u00f3n\"  data-responsive-font=\"section_title\" data-responsive-font-settings=\"{&quot;base-font-size&quot;:&quot;global&quot;,&quot;font-size&quot;:{&quot;desktop_large&quot;:&quot;70&quot;},&quot;base-line-height&quot;:&quot;global&quot;,&quot;line-height&quot;:{&quot;desktop_large&quot;:&quot;70&quot;},&quot;base-letter-spacing&quot;:&quot;global&quot;,&quot;letter-spacing&quot;:{&quot;desktop_large&quot;:&quot;-0.03&quot;}}\" class=\"section-title\"><span>Gesti\u00f3n y planificaci\u00f3n<\/span><\/h2><\/div><div data-delay=\"0\" class=\"lead\"><p>Del servicio dom\u00e9stico<\/p>\n<\/div><\/header><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>La gesti\u00f3n y planificaci\u00f3n de personas siempre ha sido uno de los retos m\u00e1s complicados en cualquier trabajo.<\/p>\n<p>Se trata de dirigir a empleados que han sido escogidos o sobre los que se pretende que exista una enorme <strong>confianza<\/strong>. Este es el primer elemento que debe de darse en cualquier persona que desarrolle su actividad profesional dentro de tu hogar, de tu espacio m\u00e1s personal e \u00edntimo.<\/p>\n<p>Sin la existencia de este elemento ser\u00e1 imposible construir absolutamente nada, no importa su grado de profesionalidad, sus conocimientos en protocolo, sus dotes en la cocina\u2026<\/p>\n<p>La confianza en el servicio dom\u00e9stico va a ser la base sobre la que se asiente todo lo dem\u00e1s. A partir de aqu\u00ed se puede trabajar y recuperar a la mayor parte de los empleados. Se podr\u00eda decir que a partir de aqu\u00ed podemos encontrarnos con otros problemas menores ante los cuales s\u00ed que podemos actuar.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"wpb_content_element  vc_custom_1648816261477\"><style type=\"text\/css\">#ut_header_6a047c367e99d h3.section-title, #ut_header_6a047c367e99d h3.section-title span { color:#9ab8ac; }#ut_header_6a047c367e99d h3.section-title{ font-family: \"Vidaloka\";font-weight:400;font-style:normal; }#ut_header_6a047c367e99d h3.section-title { font-size:30px !important;line-height:30px !important;letter-spacing:-0.03em; }#ut_header_6a047c367e99d .lead ins { font-weight:bold; }#ut_header_6a047c367e99d.pt-style-4 .page-title span, #ut_header_6a047c367e99d.pt-style-4 .parallax-title span, #ut_header_6a047c367e99d.pt-style-4 .section-title span {border-color:#9ab8ac;border-width:0px;}#ut_header_6a047c367e99d h3.section-title { margin-bottom:0px; }<\/style><header id=\"ut_header_6a047c367e99d\" class=\"section-header  ut-no-title-linebreak-mobile ut-no-lead-linebreak-mobile pt-style-4 header-left header-tablet-left header-mobile-center element-with-custom-line-height\"><div class=\"element-with-custom-line-height\" ><h3 data-title=\"El Servicio Dom\u00e9stico \u00bfIgualdad de Armas?\"  data-responsive-font=\"section_title\" data-responsive-font-settings=\"{&quot;base-font-size&quot;:&quot;30&quot;,&quot;font-size-unit&quot;:&quot;px&quot;,&quot;font-size&quot;:{&quot;desktop_large&quot;:&quot;30&quot;},&quot;base-line-height&quot;:&quot;30&quot;,&quot;line-height-unit&quot;:&quot;px&quot;,&quot;line-height&quot;:{&quot;desktop_large&quot;:&quot;30&quot;},&quot;base-letter-spacing&quot;:&quot;global&quot;,&quot;letter-spacing&quot;:{&quot;desktop_large&quot;:&quot;-0.03&quot;}}\" class=\"section-title\"><span>El Servicio Dom\u00e9stico \u00bfIgualdad de Armas?<\/span><\/h3><\/div><\/header><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>En muchos hogares me encuentro con que el personal se organiza \u00e9l mismo sin que tenga ning\u00fan horario establecido adem\u00e1s de las comidas. Este es un error muy com\u00fan, pensar que el personal de la casa sabe formarse y planificarse solo de forma eficaz y eficiente y sabr\u00e1 mantener un buen ritmo y sentirse motivado a diario.<\/p>\n<p>Realmente muy pocos trabajadores de cualquier sector e industria son capaces de autogestionarse correctamente. Si eso fuera as\u00ed no existir\u00edan los departamentos de recursos humanos ni los jefes de departamento o jefes de proyectos.<\/p>\n<p>Es asombroso lo que la mayor\u00eda son capaces de hacer con la formaci\u00f3n, planificaci\u00f3n y motivaci\u00f3n adecuada. Simplemente no se les han dado las mismas armas y las mismas oportunidades que al resto de los trabajadores y se les ha exigido m\u00e1s.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3><span style=\"color: #9ab8ac;\"><strong>ELEMENTOS NECESARIOS PARA MEJORAR LA JORNADA LABORAL DEL SERVICIO DOM\u00c9STICO<br \/>\n<\/strong><\/span><\/h3>\n<p>Existen una serie de elementos necesarios al objeto de mejorar el desarrollo de la jornada laboral en todos sus aspectos (rapidez, calidad, capacidad de trabajo, fatiga f\u00edsica y mental\u2026). No voy a enumerar todos pero si que voy a decir cu\u00e1les son a mi juicio las mas relevantes:<\/p>\n<p>&nbsp;<\/p>\n<h4><span style=\"color: #9ab8ac;\"><strong>01 Planificaci\u00f3n<\/strong><\/span><\/h4>\n<hr \/>\n<p>El personal de servicio dom\u00e9stico no conoce tus <strong>prioridades<\/strong> y si no se las dices va a ser incapaz de adivinarlas. Todo ello sin mencionar que dichas prioridades pueden cambiar si cambian las circunstancias, por lo que, adem\u00e1s de que siempre exista una comunicaci\u00f3n fluida con el mismo, es necesario que se planifiquen las jornadas ordinarias (el d\u00eda a d\u00eda laboral y festivo) as\u00ed como las extraordinarias (cenas, eventos, invitados\u2026).<\/p>\n<p>Deben de marcarse una serie de tareas diarias con sus <strong>franjas horarias<\/strong> de forma que cuando termine dicha franja horaria d\u00e9 comienzo la siguiente tarea programada.<\/p>\n<p>Por otro lado, en la planificaci\u00f3n tendremos en cuenta <strong>tareas diarias, tareas semanales y tareas mensuales<\/strong>. Por ejemplo, una tarea diaria ser\u00e1 limpiar los ba\u00f1os, una semanal ser\u00e1 la de limpiar al fondo el sal\u00f3n y una mensual ser\u00e1 la de limpiar a fondo la nevera.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4><span style=\"color: #9ab8ac;\"><strong>02 Formaci\u00f3n<\/strong><\/span><\/h4>\n<hr \/>\n<p>Gran parte de mi trabajo es dar formaci\u00f3n al servicio dom\u00e9stico de forma que sean capaces de afrontar las tareas del d\u00eda a d\u00eda de manera m\u00e1s r\u00e1pida y eficaz.<\/p>\n<p>Es curioso ver como <strong>cuanto m\u00e1s aprenden m\u00e1s quieren aprender<\/strong> y como el desarrollo de su trabajo se realiza de forma m\u00e1s proactiva.<\/p>\n<p>La seguridad de poder llamar a alguien ante cualquier duda o problema, respaldo que tienen la mayor\u00eda de los trabajadores de cualquier otro sector, les anima a asumir m\u00e1s responsabilidades y a una mayor involucraci\u00f3n en el trabajo. Es imposible formar a buenos profesionales si no les facilitas las <strong>herramientas necesarias para que se produzca ese crecimiento<\/strong>.<\/p>\n<p>Es muy complicado resumir en qu\u00e9 consiste dicha formaci\u00f3n es unas l\u00edneas dado que se trata de conocimientos que se han ido adquiriendo a medida que se han ido superando la mayor parte de problemas que suelen darse en el d\u00eda a d\u00eda.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4><strong><span style=\"color: #9ab8ac;\">03 Gesti\u00f3n<\/span><\/strong><\/h4>\n<hr \/>\n<p>Debemos <strong>conocer las fortalezas y debilidades<\/strong> de nuestros trabajadores dado que son estas las que van a determinar cu\u00e1les van a ser los trabajos que mejor desarrollen y que m\u00e1s les guste hacer.<\/p>\n<p>En el caso de desconocerlas es una buena opci\u00f3n hacer rotaciones de forma que demos la oportunidad a los integrantes del servicio dom\u00e9stico de la casa a probar.<\/p>\n<p>No suele ser este el caso de la mayor parte de las casas a las que asisto, estos roles suelen estar muy determinados y como mucho es en las nuevas incorporaciones en donde se pueden modificar para que el equipo trabaje lo mejor posible y en la mejor sinton\u00eda.<\/p>\n<p>Respecto a esto \u00faltimo, debemos de tener cuidado cuando se den incorporaciones nuevas dado que es un momento delicado. He visto en ocasiones como el nuevo supera ostensiblemente en determinados conocimientos a alg\u00fan integrante del equipo el cual se siente amenazado y en vez de demostrar su val\u00eda en el trabajo opta por intentar infundir miedo con artima\u00f1as con el resto del equipo.<\/p>\n<p>Debemos de evitar este tipo de enfrentamientos que pueden provocar desmotivaci\u00f3n o miedo en una nueva incorporaci\u00f3n dado que podemos perder a un integrante del equipo muy valioso.<\/p>\n<p>Debemos cuidar la nueva incorporaci\u00f3n d\u00e1ndole much\u00edsima confianza y haci\u00e9ndole ver la importancia que tiene para nosotros el que se sume al equipo y que nos avise de cualquier conducta extra\u00f1a.<\/p>\n<p>Por otro lado, debemos de fomentar el sentimiento de <strong>equipo<\/strong> entre todos los integrantes para que exista <strong>buen ambiente<\/strong> y la ayuda mutua. Solo teniendo la confianza real de todo el equipo seremos capaces nosotros de aportarles lo que de verdad necesitan ellos para trabajar y sentirse <strong>a gusto<\/strong>.<\/p>\n<p>Un equipo de trabajo que no es feliz en una casa jam\u00e1s va a dar lo mejor as\u00ed que gran parte de nuestro trabajo es trabajar en su felicidad y en su confianza.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div id=\"ut-row-6a047c36ad8d9\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_column-gap-0 vc_row-o-equal-height vc_row-flex ut-row-6a047c36ad8e5\" ><div class=\"wpb_column vc_column_container vc_col-sm-4\" ><div id=\"ut_inner_column_6a047c36ae0cc\" class=\"vc_column-inner\" ><div class=\"wpb_wrapper\"><div  class=\"wpb_content_element   clearfix\"><style type=\"text\/css\">#ut_am_6a047c36ae678 { opacity: 1; }#ut_am_wrap_6a047c36ae67a .ut-image-gallery-item-caption-title h3 { letter-spacing: 0em; }#ut_am_wrap_6a047c36ae67a .ut-gallery-slider-caption { font-weight: bold; }#ut_am_wrap_6a047c36ae67a { text-align: left; }@media (min-width: 768px) and (max-width: 1024px) { #ut_am_wrap_6a047c36ae67a { text-align: left !important; } }@media (max-width: 767px) { #ut_am_wrap_6a047c36ae67a { text-align: center !important; } }<\/style><div id=\"ut_am_wrap_6a047c36ae67a\" class=\"ut-image-gallery-image\"><div id=\"ut_reveal_6a047c36ae67b\"  data-appear-top-offset=\"auto\" class=\"ut-animated-image-item ut-image-gallery-item ut-animation-done\"><a class=\"ut-deactivated-link\" href=\"#\"><div class=\"ut-animated-image-zoom\"><img class=\"ut-lazy skip-lazy ut-animated-image\"  id=\"ut_am_6a047c36ae678\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 1280 1920'%2F%3E\" data-src=\"https:\/\/ordertactics.es\/wp-content\/uploads\/2022\/09\/planificacion-domestica-por-alex-02.jpg\" width=\"1280\" height=\"1920\" alt=\"planificacion domestica por alex\"\/><\/div><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-8\" ><div id=\"ut_inner_column_6a047c36aea42\" class=\"vc_column-inner\" ><div class=\"wpb_wrapper\"><div class=\"wpb_content_element\"><style type=\"text\/css\">#ut_header_6a047c36af2f6 h2.section-title { font-size:70px !important;line-height:70px !important;letter-spacing:-0.03em; }<\/style><header id=\"ut_header_6a047c36af2f6\" class=\"section-header  ut-no-title-linebreak-mobile ut-no-lead-linebreak-mobile pt-style-2 header-left header-tablet-left header-mobile-center element-with-custom-line-height\"><div class=\"element-with-custom-line-height\" ><h2 data-title=\"Resumen\"  data-responsive-font=\"section_title\" data-responsive-font-settings=\"{&quot;base-font-size&quot;:&quot;global&quot;,&quot;font-size&quot;:{&quot;desktop_large&quot;:&quot;70&quot;},&quot;base-line-height&quot;:&quot;global&quot;,&quot;line-height&quot;:{&quot;desktop_large&quot;:&quot;70&quot;},&quot;base-letter-spacing&quot;:&quot;global&quot;,&quot;letter-spacing&quot;:{&quot;desktop_large&quot;:&quot;-0.03&quot;}}\" class=\"section-title\"><span>Summary<\/span><\/h2><\/div><div data-delay=\"0\" class=\"lead\"><p>Management and planning of domestic service<\/p>\n<\/div><\/header><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>En resumen, se podr\u00eda decir que me he encontrado en muchas casas personal del servicio dom\u00e9stico que no funcionaban por que nadie les hab\u00eda ense\u00f1ado a planificarse ni a realizar las tareas correctamente y esta situaci\u00f3n es dif\u00edcil de sostener en ambos lados: la persona cree que el trabajo le supera y la due\u00f1a de la casa siente que no se est\u00e1 trabajando lo que se deber\u00eda. El resultado de dar formaci\u00f3n es ver como el servicio dom\u00e9stico realmente se siente valorado, capaz de trabajar al 100% tranquilamente en vez de trabajar al 60% al l\u00edmite y totalmente saturado.<\/p>\n<p>\u00bfTe gustar\u00eda obtener un presupuesto personalizado para la formaci\u00f3n de tu servicio dom\u00e9stico?<a href=\"https:\/\/ordertactics.es\/en\/contact\/\"> Clic aqu\u00ed<\/a>.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div id=\"ut-row-6a047c371dff2\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_column-gap-0 ut-row-6a047c371dffb\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\" ><div id=\"ut_inner_column_6a047c371e4e0\" class=\"vc_column-inner\" ><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>I hope you found this article interesting and enjoyed it. Share and comment!<\/p>\n<p><a href=\"https:\/\/ordertactics.es\/wp-content\/uploads\/2022\/02\/alexandra-m.png\"><img loading=\"lazy\" class=\"alignnone wp-image-3304\" src=\"https:\/\/ordertactics.es\/wp-content\/uploads\/2022\/02\/alexandra-m.png\" alt=\"\" width=\"120\" height=\"22\" \/><\/a><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div  class=\"wpb_content_element   clearfix\"><style type=\"text\/css\">#ut_am_6a047c371eab9 { opacity: 1; }#ut_am_wrap_6a047c371eaba .ut-image-gallery-item-caption-title h3 { letter-spacing: 0em; }#ut_am_wrap_6a047c371eaba .ut-gallery-slider-caption { font-weight: bold; }#ut_am_wrap_6a047c371eaba { text-align: left; }@media (min-width: 768px) and (max-width: 1024px) { #ut_am_wrap_6a047c371eaba { text-align: left !important; } }@media (max-width: 767px) { #ut_am_wrap_6a047c371eaba { text-align: center !important; } }<\/style><div id=\"ut_am_wrap_6a047c371eaba\" class=\"ut-image-gallery-image\"><div id=\"ut_reveal_6a047c371eabb\"  data-appear-top-offset=\"auto\" class=\"ut-animated-image-item ut-image-gallery-item ut-animation-done\"><a class=\"ut-deactivated-link\" href=\"#\"><div class=\"ut-animated-image-zoom\"><img class=\"ut-lazy skip-lazy ut-animated-image\"  id=\"ut_am_6a047c371eab9\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 1920 1281'%2F%3E\" data-src=\"https:\/\/ordertactics.es\/wp-content\/uploads\/2022\/09\/planificacion-domestica-por-alex-03.jpg\" width=\"1920\" height=\"1281\" alt=\"planificacion domestica\"\/><\/div><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><a data-id=\"section-without-id\" class=\"ut-vc-offset-anchor-bottom\" name=\"section-without-id\"><\/a><\/section><div class=\"vc_row-full-width vc_clearfix\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Training domestic workers is key to improving working hours.<\/p>","protected":false},"author":2,"featured_media":3605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,17],"tags":[39,37,36,38,35,29,19,27,20,23,34],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gesti\u00f3n y planificaci\u00f3n del servicio dom\u00e9stico - Order Tactics<\/title>\n<meta name=\"description\" content=\"La gesti\u00f3n, planificaci\u00f3n y formaci\u00f3n del servicio dom\u00e9stico es clave para que quieran aprender y mejorar el trabajo en el hogar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ordertactics.es\/en\/alex-m-organizer\/gestion-y-planificacion-del-servicio-domestico\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gesti\u00f3n y planificaci\u00f3n del servicio dom\u00e9stico - Order Tactics\" \/>\n<meta property=\"og:description\" content=\"La gesti\u00f3n, planificaci\u00f3n y formaci\u00f3n del servicio dom\u00e9stico es clave para que quieran aprender y mejorar el trabajo en el hogar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ordertactics.es\/en\/alex-m-organizer\/gestion-y-planificacion-del-servicio-domestico\/\" \/>\n<meta property=\"og:site_name\" content=\"Order Tactics\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-31T11:54:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-01T13:14:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ordertactics.es\/wp-content\/uploads\/2022\/09\/planificacion-domestica-por-alex-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Talcualideas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ordertactics.es\/#website\",\"url\":\"https:\/\/ordertactics.es\/\",\"name\":\"Order Tactics\",\"description\":\"Organizing your world\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ordertactics.es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/ordertactics.es\/alex-m-organizadora\/gestion-y-planificacion-del-servicio-domestico\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/ordertactics.es\/wp-content\/uploads\/2022\/09\/planificacion-domestica-por-alex-01.jpg\",\"contentUrl\":\"https:\/\/ordertactics.es\/wp-content\/uploads\/2022\/09\/planificacion-domestica-por-alex-01.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"planificacion domestica\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ordertactics.es\/alex-m-organizadora\/gestion-y-planificacion-del-servicio-domestico\/#webpage\",\"url\":\"https:\/\/ordertactics.es\/alex-m-organizadora\/gestion-y-planificacion-del-servicio-domestico\/\",\"name\":\"Gesti\u00f3n y planificaci\u00f3n del servicio dom\u00e9stico - Order Tactics\",\"isPartOf\":{\"@id\":\"https:\/\/ordertactics.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ordertactics.es\/alex-m-organizadora\/gestion-y-planificacion-del-servicio-domestico\/#primaryimage\"},\"datePublished\":\"2022-03-31T11:54:53+00:00\",\"dateModified\":\"2022-04-01T13:14:59+00:00\",\"author\":{\"@id\":\"https:\/\/ordertactics.es\/#\/schema\/person\/c35d38aba434572d9f27c7260eaa77b3\"},\"description\":\"La gesti\u00f3n, planificaci\u00f3n y formaci\u00f3n del servicio dom\u00e9stico es clave para que quieran aprender y mejorar el trabajo en el hogar.\",\"breadcrumb\":{\"@id\":\"https:\/\/ordertactics.es\/alex-m-organizadora\/gestion-y-planificacion-del-servicio-domestico\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ordertactics.es\/alex-m-organizadora\/gestion-y-planificacion-del-servicio-domestico\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ordertactics.es\/alex-m-organizadora\/gestion-y-planificacion-del-servicio-domestico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ordertactics.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gesti\u00f3n y planificaci\u00f3n del servicio dom\u00e9stico\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/ordertactics.es\/#\/schema\/person\/c35d38aba434572d9f27c7260eaa77b3\",\"name\":\"Talcualideas\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/ordertactics.es\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2b97befa3a29032a41f86300d10eb4de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2b97befa3a29032a41f86300d10eb4de?s=96&d=mm&r=g\",\"caption\":\"Talcualideas\"},\"url\":\"https:\/\/ordertactics.es\/en\/author\/talcualideas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gesti\u00f3n y planificaci\u00f3n del servicio dom\u00e9stico - Order Tactics","description":"La gesti\u00f3n, planificaci\u00f3n y formaci\u00f3n del servicio dom\u00e9stico es clave para que quieran aprender y mejorar el trabajo en el hogar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ordertactics.es\/en\/alex-m-organizer\/gestion-y-planificacion-del-servicio-domestico\/","og_locale":"en_US","og_type":"article","og_title":"Gesti\u00f3n y planificaci\u00f3n del servicio dom\u00e9stico - Order Tactics","og_description":"La gesti\u00f3n, planificaci\u00f3n y formaci\u00f3n del servicio dom\u00e9stico es clave para que quieran aprender y mejorar el trabajo en el hogar.","og_url":"https:\/\/ordertactics.es\/en\/alex-m-organizer\/gestion-y-planificacion-del-servicio-domestico\/","og_site_name":"Order Tactics","article_published_time":"2022-03-31T11:54:53+00:00","article_modified_time":"2022-04-01T13:14:59+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/ordertactics.es\/wp-content\/uploads\/2022\/09\/planificacion-domestica-por-alex-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Talcualideas","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/ordertactics.es\/#website","url":"https:\/\/ordertactics.es\/","name":"Order Tactics","description":"Organizing your world","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ordertactics.es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/ordertactics.es\/alex-m-organizadora\/gestion-y-planificacion-del-servicio-domestico\/#primaryimage","inLanguage":"en-US","url":"https:\/\/ordertactics.es\/wp-content\/uploads\/2022\/09\/planificacion-domestica-por-alex-01.jpg","contentUrl":"https:\/\/ordertactics.es\/wp-content\/uploads\/2022\/09\/planificacion-domestica-por-alex-01.jpg","width":1920,"height":1280,"caption":"planificacion domestica"},{"@type":"WebPage","@id":"https:\/\/ordertactics.es\/alex-m-organizadora\/gestion-y-planificacion-del-servicio-domestico\/#webpage","url":"https:\/\/ordertactics.es\/alex-m-organizadora\/gestion-y-planificacion-del-servicio-domestico\/","name":"Gesti\u00f3n y planificaci\u00f3n del servicio dom\u00e9stico - Order Tactics","isPartOf":{"@id":"https:\/\/ordertactics.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ordertactics.es\/alex-m-organizadora\/gestion-y-planificacion-del-servicio-domestico\/#primaryimage"},"datePublished":"2022-03-31T11:54:53+00:00","dateModified":"2022-04-01T13:14:59+00:00","author":{"@id":"https:\/\/ordertactics.es\/#\/schema\/person\/c35d38aba434572d9f27c7260eaa77b3"},"description":"La gesti\u00f3n, planificaci\u00f3n y formaci\u00f3n del servicio dom\u00e9stico es clave para que quieran aprender y mejorar el trabajo en el hogar.","breadcrumb":{"@id":"https:\/\/ordertactics.es\/alex-m-organizadora\/gestion-y-planificacion-del-servicio-domestico\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ordertactics.es\/alex-m-organizadora\/gestion-y-planificacion-del-servicio-domestico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ordertactics.es\/alex-m-organizadora\/gestion-y-planificacion-del-servicio-domestico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ordertactics.es\/"},{"@type":"ListItem","position":2,"name":"Gesti\u00f3n y planificaci\u00f3n del servicio dom\u00e9stico"}]},{"@type":"Person","@id":"https:\/\/ordertactics.es\/#\/schema\/person\/c35d38aba434572d9f27c7260eaa77b3","name":"Talcualideas","image":{"@type":"ImageObject","@id":"https:\/\/ordertactics.es\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/2b97befa3a29032a41f86300d10eb4de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b97befa3a29032a41f86300d10eb4de?s=96&d=mm&r=g","caption":"Talcualideas"},"url":"https:\/\/ordertactics.es\/en\/author\/talcualideas\/"}]}},"_links":{"self":[{"href":"https:\/\/ordertactics.es\/en\/wp-json\/wp\/v2\/posts\/3597"}],"collection":[{"href":"https:\/\/ordertactics.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ordertactics.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ordertactics.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ordertactics.es\/en\/wp-json\/wp\/v2\/comments?post=3597"}],"version-history":[{"count":14,"href":"https:\/\/ordertactics.es\/en\/wp-json\/wp\/v2\/posts\/3597\/revisions"}],"predecessor-version":[{"id":3614,"href":"https:\/\/ordertactics.es\/en\/wp-json\/wp\/v2\/posts\/3597\/revisions\/3614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ordertactics.es\/en\/wp-json\/wp\/v2\/media\/3605"}],"wp:attachment":[{"href":"https:\/\/ordertactics.es\/en\/wp-json\/wp\/v2\/media?parent=3597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ordertactics.es\/en\/wp-json\/wp\/v2\/categories?post=3597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ordertactics.es\/en\/wp-json\/wp\/v2\/tags?post=3597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}